{"id":2081,"date":"2022-11-14T19:32:22","date_gmt":"2022-11-14T18:32:22","guid":{"rendered":"http:\/\/tsv-ettlingen.de\/tsv\/?p=2081"},"modified":"2022-11-24T16:04:08","modified_gmt":"2022-11-24T15:04:08","slug":"u18m-mit-erstem-haertetest","status":"publish","type":"post","link":"https:\/\/tsv-ettlingen.de\/tsv\/u18m-mit-erstem-haertetest","title":{"rendered":"U18m mit erstem H\u00e4rtetest"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Am vergangenen Samstag (12.11.22) mussten sich die U18-Jungs des TSV Ettlingen gegen den starken Gegner TSV Berghausen in einer Ausw\u00e4rtspartie mit 54:73 geschlagen geben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nach einer langen Spielpause und mit einem deutlichen ersten Sieg in Durlach (56:28 am 02.10.22) im R\u00fccken, reisten die 11 Spieler des TSV Ettlingen in Berghausen an. Ein vorheriger Blick in die Tabelle der U18-Bezirksliga machte Jedem klar, welcher Gegner sich den G\u00e4sten heute bieten sollte. Berghausen spielte bis Dato 3 Spiele und gewann jedes mit einem klaren Vorsprung. Vor allem deren Center-Spieler und Werfer galt es besondere Aufmerksamkeit zu widmen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Direkt zu beginn zeigte der bisherige Topscorer der Gegner, dass er sowohl mit Zug zum Korb als auch von der 3er-Linie eine Gefahr darstellt und erzielte in kurzer Zeit 16 Punkte im Alleingang. Die logische Folge: Ettlingen spielte aus der Not fr\u00fch eine &#8222;Box-and-one&#8220;-Verteidigung und setzten Abwehrriegel Schimmer auf den Spieler an. Mit dieser einzelnen Mann-Verteidigung konnte Ettlingen bis zur Halbzeitpause den korbgef\u00e4hrlichsten Spieler der Gegner fast vollst\u00e4ndig aus dem Spiel nehmen und gleichzeitig wieder selbst zur\u00fcck ins Spiel kommen. Offensiv wirbelte dabei vor allem Aufbauspieler Mahler mit guten Abschl\u00fcssen und Entscheidungen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Somit konnte dann nach der Findungsphase im ersten Viertel, zum zweiten Viertel wieder der Anschluss generiert werden, dass es zur Halbzeitpause mit nur 2 Punkten R\u00fcckstand in ein Zwischenres\u00fcmee ging:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Weiter auf die Aufbauspieler Druck aus\u00fcben, den gef\u00e4hrlichen gegnerischen Center aus dem Spiel halten und die gut geworfenen Dreier der Heimmannschaft konsequent verteidigen hie\u00df das Motto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Leider hatte Berghausen zu diesem Zeitpunkt ein gutes Rezept gegen die bis dahin effektive Verteidigung des TSV gefunden und konzentrierte sich auf W\u00fcrfe von Au\u00dfen, welche meistens auch von Erfolg gekr\u00f6nt waren. Dadurch konnten sie den Ettlinger Korbj\u00e4gern im 3. Viertel mit 62-40 davonziehen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mit Kampfgeist konnten vorallem Pr\u00fcfer, Schimmer und Frank das Ergebnis im letzten Viertel verbessern und zum Schlussstand von 54:73 Punkten beitragen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Insgesamt zeigten die G\u00e4ste aus Ettlingen, dass sie auch starken Teams gewachsen sind und Etappenweise sehr wohl gut auf Augen\u00f6he mitspielen k\u00f6nnen. Ebenso konnte Einiges gelernt werden und die Spieler sehen mit hohen Erwartungen dem R\u00fcckspiel entgegen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>TSV Berghausen \u2013 TSV Ettlingen 73:54<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Es spielten: <\/em><\/strong>Mahler (13), Schimmer (13), Pr\u00fcfer (8), Seidler (6), Frank (4), Schehl (4), Voigts-Rhetz (4), Rakin (2), Bajraktarevic, Wild, Zimmer<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am vergangenen Samstag (12.11.22) mussten sich die U18-Jungs des TSV Ettlingen gegen den starken Gegner TSV Berghausen in einer Ausw\u00e4rtspartie mit 54:73 geschlagen geben. Nach einer langen Spielpause und mit einem deutlichen ersten Sieg in Durlach (56:28 am 02.10.22) im R\u00fccken, reisten die 11 Spieler des TSV Ettlingen in Berghausen an. Ein vorheriger Blick in&hellip;&nbsp;<a href=\"https:\/\/tsv-ettlingen.de\/tsv\/u18m-mit-erstem-haertetest\" rel=\"bookmark\">Weiterlesen &raquo;<span class=\"screen-reader-text\">U18m mit erstem H\u00e4rtetest<\/span><\/a><\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[18],"tags":[96,143],"class_list":["post-2081","post","type-post","status-publish","format-standard","hentry","category-basketball","tag-tsv-ettlingen","tag-u18"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>U18m mit erstem H\u00e4rtetest - TSV Ettlingen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tsv-ettlingen.de\/tsv\/u18m-mit-erstem-haertetest\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"U18m mit erstem H\u00e4rtetest - TSV Ettlingen\" \/>\n<meta property=\"og:description\" content=\"Am vergangenen Samstag (12.11.22) mussten sich die U18-Jungs des TSV Ettlingen gegen den starken Gegner TSV Berghausen in einer Ausw\u00e4rtspartie mit 54:73 geschlagen geben. Nach einer langen Spielpause und mit einem deutlichen ersten Sieg in Durlach (56:28 am 02.10.22) im R\u00fccken, reisten die 11 Spieler des TSV Ettlingen in Berghausen an. Ein vorheriger Blick in&hellip;&nbsp;Weiterlesen &raquo;U18m mit erstem H\u00e4rtetest\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tsv-ettlingen.de\/tsv\/u18m-mit-erstem-haertetest\" \/>\n<meta property=\"og:site_name\" content=\"TSV Ettlingen\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-14T18:32:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-24T15:04:08+00:00\" \/>\n<meta name=\"author\" content=\"TSV Redaktion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"TSV Redaktion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/u18m-mit-erstem-haertetest#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/u18m-mit-erstem-haertetest\"},\"author\":{\"name\":\"TSV Redaktion\",\"@id\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/#\\\/schema\\\/person\\\/88a6f1b991e30ca7b1af83077ebd72e7\"},\"headline\":\"U18m mit erstem H\u00e4rtetest\",\"datePublished\":\"2022-11-14T18:32:22+00:00\",\"dateModified\":\"2022-11-24T15:04:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/u18m-mit-erstem-haertetest\"},\"wordCount\":383,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/#organization\"},\"keywords\":[\"TSV Ettlingen\",\"U18\"],\"articleSection\":[\"Basketball\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/u18m-mit-erstem-haertetest#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/u18m-mit-erstem-haertetest\",\"url\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/u18m-mit-erstem-haertetest\",\"name\":\"U18m mit erstem H\u00e4rtetest - TSV Ettlingen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/#website\"},\"datePublished\":\"2022-11-14T18:32:22+00:00\",\"dateModified\":\"2022-11-24T15:04:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/u18m-mit-erstem-haertetest#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/u18m-mit-erstem-haertetest\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/u18m-mit-erstem-haertetest#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"U18m mit erstem H\u00e4rtetest\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/#website\",\"url\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/\",\"name\":\"TSV Ettlingen\",\"description\":\"Zusammenhalt leben!\",\"publisher\":{\"@id\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/#organization\",\"name\":\"TSV Ettlingen e.V.\",\"url\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/LOGO_Farbe.jpg\",\"contentUrl\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/LOGO_Farbe.jpg\",\"width\":2008,\"height\":1181,\"caption\":\"TSV Ettlingen e.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/tsv_ettlingen\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/#\\\/schema\\\/person\\\/88a6f1b991e30ca7b1af83077ebd72e7\",\"name\":\"TSV Redaktion\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e95bea8796f91ba1b6b19a2f5d5f1110412d838f637eede0fd17531ded334a5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e95bea8796f91ba1b6b19a2f5d5f1110412d838f637eede0fd17531ded334a5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e95bea8796f91ba1b6b19a2f5d5f1110412d838f637eede0fd17531ded334a5?s=96&d=mm&r=g\",\"caption\":\"TSV Redaktion\"},\"url\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/author\\\/tsv-redaktion\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"U18m mit erstem H\u00e4rtetest - TSV Ettlingen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tsv-ettlingen.de\/tsv\/u18m-mit-erstem-haertetest","og_locale":"de_DE","og_type":"article","og_title":"U18m mit erstem H\u00e4rtetest - TSV Ettlingen","og_description":"Am vergangenen Samstag (12.11.22) mussten sich die U18-Jungs des TSV Ettlingen gegen den starken Gegner TSV Berghausen in einer Ausw\u00e4rtspartie mit 54:73 geschlagen geben. Nach einer langen Spielpause und mit einem deutlichen ersten Sieg in Durlach (56:28 am 02.10.22) im R\u00fccken, reisten die 11 Spieler des TSV Ettlingen in Berghausen an. Ein vorheriger Blick in&hellip;&nbsp;Weiterlesen &raquo;U18m mit erstem H\u00e4rtetest","og_url":"https:\/\/tsv-ettlingen.de\/tsv\/u18m-mit-erstem-haertetest","og_site_name":"TSV Ettlingen","article_published_time":"2022-11-14T18:32:22+00:00","article_modified_time":"2022-11-24T15:04:08+00:00","author":"TSV Redaktion","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"TSV Redaktion","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tsv-ettlingen.de\/tsv\/u18m-mit-erstem-haertetest#article","isPartOf":{"@id":"https:\/\/tsv-ettlingen.de\/tsv\/u18m-mit-erstem-haertetest"},"author":{"name":"TSV Redaktion","@id":"https:\/\/tsv-ettlingen.de\/tsv\/#\/schema\/person\/88a6f1b991e30ca7b1af83077ebd72e7"},"headline":"U18m mit erstem H\u00e4rtetest","datePublished":"2022-11-14T18:32:22+00:00","dateModified":"2022-11-24T15:04:08+00:00","mainEntityOfPage":{"@id":"https:\/\/tsv-ettlingen.de\/tsv\/u18m-mit-erstem-haertetest"},"wordCount":383,"commentCount":0,"publisher":{"@id":"https:\/\/tsv-ettlingen.de\/tsv\/#organization"},"keywords":["TSV Ettlingen","U18"],"articleSection":["Basketball"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tsv-ettlingen.de\/tsv\/u18m-mit-erstem-haertetest#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tsv-ettlingen.de\/tsv\/u18m-mit-erstem-haertetest","url":"https:\/\/tsv-ettlingen.de\/tsv\/u18m-mit-erstem-haertetest","name":"U18m mit erstem H\u00e4rtetest - TSV Ettlingen","isPartOf":{"@id":"https:\/\/tsv-ettlingen.de\/tsv\/#website"},"datePublished":"2022-11-14T18:32:22+00:00","dateModified":"2022-11-24T15:04:08+00:00","breadcrumb":{"@id":"https:\/\/tsv-ettlingen.de\/tsv\/u18m-mit-erstem-haertetest#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tsv-ettlingen.de\/tsv\/u18m-mit-erstem-haertetest"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/tsv-ettlingen.de\/tsv\/u18m-mit-erstem-haertetest#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/tsv-ettlingen.de\/tsv\/"},{"@type":"ListItem","position":2,"name":"U18m mit erstem H\u00e4rtetest"}]},{"@type":"WebSite","@id":"https:\/\/tsv-ettlingen.de\/tsv\/#website","url":"https:\/\/tsv-ettlingen.de\/tsv\/","name":"TSV Ettlingen","description":"Zusammenhalt leben!","publisher":{"@id":"https:\/\/tsv-ettlingen.de\/tsv\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tsv-ettlingen.de\/tsv\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/tsv-ettlingen.de\/tsv\/#organization","name":"TSV Ettlingen e.V.","url":"https:\/\/tsv-ettlingen.de\/tsv\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/tsv-ettlingen.de\/tsv\/#\/schema\/logo\/image\/","url":"https:\/\/tsv-ettlingen.de\/tsv\/wp-content\/uploads\/2021\/05\/LOGO_Farbe.jpg","contentUrl":"https:\/\/tsv-ettlingen.de\/tsv\/wp-content\/uploads\/2021\/05\/LOGO_Farbe.jpg","width":2008,"height":1181,"caption":"TSV Ettlingen e.V."},"image":{"@id":"https:\/\/tsv-ettlingen.de\/tsv\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/tsv_ettlingen\/"]},{"@type":"Person","@id":"https:\/\/tsv-ettlingen.de\/tsv\/#\/schema\/person\/88a6f1b991e30ca7b1af83077ebd72e7","name":"TSV Redaktion","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/3e95bea8796f91ba1b6b19a2f5d5f1110412d838f637eede0fd17531ded334a5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3e95bea8796f91ba1b6b19a2f5d5f1110412d838f637eede0fd17531ded334a5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3e95bea8796f91ba1b6b19a2f5d5f1110412d838f637eede0fd17531ded334a5?s=96&d=mm&r=g","caption":"TSV Redaktion"},"url":"https:\/\/tsv-ettlingen.de\/tsv\/author\/tsv-redaktion"}]}},"_links":{"self":[{"href":"https:\/\/tsv-ettlingen.de\/tsv\/wp-json\/wp\/v2\/posts\/2081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tsv-ettlingen.de\/tsv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tsv-ettlingen.de\/tsv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tsv-ettlingen.de\/tsv\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/tsv-ettlingen.de\/tsv\/wp-json\/wp\/v2\/comments?post=2081"}],"version-history":[{"count":2,"href":"https:\/\/tsv-ettlingen.de\/tsv\/wp-json\/wp\/v2\/posts\/2081\/revisions"}],"predecessor-version":[{"id":2117,"href":"https:\/\/tsv-ettlingen.de\/tsv\/wp-json\/wp\/v2\/posts\/2081\/revisions\/2117"}],"wp:attachment":[{"href":"https:\/\/tsv-ettlingen.de\/tsv\/wp-json\/wp\/v2\/media?parent=2081"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tsv-ettlingen.de\/tsv\/wp-json\/wp\/v2\/categories?post=2081"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tsv-ettlingen.de\/tsv\/wp-json\/wp\/v2\/tags?post=2081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}