{"id":2305,"date":"2023-02-04T07:47:30","date_gmt":"2023-02-04T06:47:30","guid":{"rendered":"http:\/\/tsv-ettlingen.de\/tsv\/?p=2305"},"modified":"2023-02-13T19:29:50","modified_gmt":"2023-02-13T18:29:50","slug":"9-heimspieltag-am-04-05-02-2023","status":"publish","type":"post","link":"https:\/\/tsv-ettlingen.de\/tsv\/9-heimspieltag-am-04-05-02-2023","title":{"rendered":"9. Heimspieltag am 04.\/05.02.2023"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">An diesem Wochenende steht der n\u00e4chste Heimspieltag der TSVE Basketballer an und findet in der Eichendorffhalle statt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die <strong>Oberliga Frauen<\/strong> erwarten am Samstag um 19.45 Uhr die SG Mannheim zu einem echten Topspiel. Beide liegen dicht hinter den beiden Spitzenteams Sandhausen 2 und USC Heidelberg 3, die ja nicht aufsteigen k\u00f6nnen, da schon ein Team ihres Vereins in der Regionalliga spielt. Ein Sieg heute w\u00e4re also ein gro\u00dfer Schritt Richtung Tabellenspitze.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die <strong>Oberliga M\u00e4nner<\/strong> haben zuvor um 17:30 Uhr die SG Mannheim 2 zu Gast. Mannheim liegt auf dem 4. Platz in Lauerstellung hinter dem Spitzentrio der Liga. Dagegen ben\u00f6tigen die Ettlinger endlich den ersten Saisonheimsieg um vom Tabellenende wegzukommen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Schon um 11:15 Uhr beginnt der Basketballtag mit dem Spiel der <strong>U14 weiblich<\/strong> gegen den SSC Karlsruhe. Beide Teams haben sich in den letzten Spielen gut verbessert pr\u00e4sentiert, werden den beiden Spitzenteams die Pl\u00e4tze f\u00fcr die Bezirksmeisterschaft aber nicht mehr streitig machen k\u00f6nnen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Um 13.15 Uhr geht es f\u00fcr die <strong>U14 m\u00e4nnlich<\/strong> gegen die Kehler Turnerschaft. Vielleicht klappt es ja nun mit dem ersten Saisonsieg f\u00fcr die jungen Ettlinger in der starken Bezirksliga Mitte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Um 15.15 Uhr m\u00f6chte die <strong>U16 m\u00e4nnlich<\/strong> gegen die BG Karlsbad 2 ihre wei\u00dfe Weste behalten und ihre Tabellenf\u00fchrung weiter ausbauen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Am Sonntag erwarten dann um 15:30 Uhr die <strong>Kreisliga B M\u00e4nner<\/strong> den SSC Karlsruhe 3 und will dabei ihre Tabellenf\u00fchrung ebenso behalten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zuvor geht es um 13.15 Uhr f\u00fcr die <strong>U16 weiblich<\/strong> gegen den Tabellenersten PS Karlsruhe LIONS, wenn ber\u00fccksichtigt wird, dass das ungeschlagene Team der TSG Bruchsal 2 au\u00dfer Konkurrenz am Start ist.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>.. Samstag 04.02.2023 &#8211; Eichendorff-Halle \/ TSVE<\/strong><br>11:15 U14 weiblich Bezirksliga Nord <strong>TSV Ettlingen a.K. &#8211; SSC Karlsruhe<\/strong> <br>13:15 U14 m\u00e4nnlich Bezirksliga Mitte <strong>TSV Ettlingen &#8211; Kehler Turnerschaft a.K<\/strong>. <br>15:15 U16 m\u00e4nnlich Bezirksliga Mitte <strong>TSV Ettlingen &#8211; BG Karlsbad 2<\/strong> <br>17:30 Oberliga Baden M\u00e4nner <strong>TSV Ettlingen &#8211; SG Mannheim 2 <\/strong><br>19:45 Oberliga Baden Frauen <strong>TSV Ettlingen &#8211; SG Mannheim <\/strong><br><strong>.. Sonntag 05.02.2023 &#8211; Eichendorff-Halle \/ TSVE<\/strong><br>13:15 U16 weiblich Bezirksliga Nord <strong>TSV Ettlingen &#8211; PS Karlsruhe LIONS<\/strong> <br>15:30 Kreisliga B Nord M\u00e4nner <strong>TSV Ettlingen 3 &#8211; SSC Karlsruhe 3 <\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>An diesem Wochenende steht der n\u00e4chste Heimspieltag der TSVE Basketballer an und findet in der Eichendorffhalle statt. Die Oberliga Frauen erwarten am Samstag um 19.45 Uhr die SG Mannheim zu einem echten Topspiel. Beide liegen dicht hinter den beiden Spitzenteams Sandhausen 2 und USC Heidelberg 3, die ja nicht aufsteigen k\u00f6nnen, da schon ein Team&hellip;&nbsp;<a href=\"https:\/\/tsv-ettlingen.de\/tsv\/9-heimspieltag-am-04-05-02-2023\" rel=\"bookmark\">Weiterlesen &raquo;<span class=\"screen-reader-text\">9. Heimspieltag am 04.\/05.02.2023<\/span><\/a><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[1,18],"tags":[],"class_list":["post-2305","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-basketball"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>9. Heimspieltag am 04.\/05.02.2023 - TSV Ettlingen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tsv-ettlingen.de\/tsv\/9-heimspieltag-am-04-05-02-2023\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"9. Heimspieltag am 04.\/05.02.2023 - TSV Ettlingen\" \/>\n<meta property=\"og:description\" content=\"An diesem Wochenende steht der n\u00e4chste Heimspieltag der TSVE Basketballer an und findet in der Eichendorffhalle statt. Die Oberliga Frauen erwarten am Samstag um 19.45 Uhr die SG Mannheim zu einem echten Topspiel. Beide liegen dicht hinter den beiden Spitzenteams Sandhausen 2 und USC Heidelberg 3, die ja nicht aufsteigen k\u00f6nnen, da schon ein Team&hellip;&nbsp;Weiterlesen &raquo;9. Heimspieltag am 04.\/05.02.2023\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tsv-ettlingen.de\/tsv\/9-heimspieltag-am-04-05-02-2023\" \/>\n<meta property=\"og:site_name\" content=\"TSV Ettlingen\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-04T06:47:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-13T18:29:50+00:00\" \/>\n<meta name=\"author\" content=\"Frank\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Frank\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/9-heimspieltag-am-04-05-02-2023#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/9-heimspieltag-am-04-05-02-2023\"},\"author\":{\"name\":\"Frank\",\"@id\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/#\\\/schema\\\/person\\\/191ec17c3ce34b00891f4f8068a07459\"},\"headline\":\"9. Heimspieltag am 04.\\\/05.02.2023\",\"datePublished\":\"2023-02-04T06:47:30+00:00\",\"dateModified\":\"2023-02-13T18:29:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/9-heimspieltag-am-04-05-02-2023\"},\"wordCount\":347,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/#organization\"},\"articleSection\":{\"1\":\"Basketball\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/9-heimspieltag-am-04-05-02-2023#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/9-heimspieltag-am-04-05-02-2023\",\"url\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/9-heimspieltag-am-04-05-02-2023\",\"name\":\"9. Heimspieltag am 04.\\\/05.02.2023 - TSV Ettlingen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/#website\"},\"datePublished\":\"2023-02-04T06:47:30+00:00\",\"dateModified\":\"2023-02-13T18:29:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/9-heimspieltag-am-04-05-02-2023#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/9-heimspieltag-am-04-05-02-2023\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/9-heimspieltag-am-04-05-02-2023#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"9. Heimspieltag am 04.\\\/05.02.2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/#website\",\"url\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/\",\"name\":\"TSV Ettlingen\",\"description\":\"Zusammenhalt leben!\",\"publisher\":{\"@id\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/#organization\",\"name\":\"TSV Ettlingen e.V.\",\"url\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/LOGO_Farbe.jpg\",\"contentUrl\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/LOGO_Farbe.jpg\",\"width\":2008,\"height\":1181,\"caption\":\"TSV Ettlingen e.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/tsv_ettlingen\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/#\\\/schema\\\/person\\\/191ec17c3ce34b00891f4f8068a07459\",\"name\":\"Frank\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b27f9d77b987be88a5739765b8f2ebb9cdd50622de5561c0cd970dae24e7f7d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b27f9d77b987be88a5739765b8f2ebb9cdd50622de5561c0cd970dae24e7f7d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b27f9d77b987be88a5739765b8f2ebb9cdd50622de5561c0cd970dae24e7f7d3?s=96&d=mm&r=g\",\"caption\":\"Frank\"},\"sameAs\":[\"http:\\\/\\\/www.spiders.de\"],\"url\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/author\\\/frankrau\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"9. Heimspieltag am 04.\/05.02.2023 - TSV Ettlingen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tsv-ettlingen.de\/tsv\/9-heimspieltag-am-04-05-02-2023","og_locale":"de_DE","og_type":"article","og_title":"9. Heimspieltag am 04.\/05.02.2023 - TSV Ettlingen","og_description":"An diesem Wochenende steht der n\u00e4chste Heimspieltag der TSVE Basketballer an und findet in der Eichendorffhalle statt. Die Oberliga Frauen erwarten am Samstag um 19.45 Uhr die SG Mannheim zu einem echten Topspiel. Beide liegen dicht hinter den beiden Spitzenteams Sandhausen 2 und USC Heidelberg 3, die ja nicht aufsteigen k\u00f6nnen, da schon ein Team&hellip;&nbsp;Weiterlesen &raquo;9. Heimspieltag am 04.\/05.02.2023","og_url":"https:\/\/tsv-ettlingen.de\/tsv\/9-heimspieltag-am-04-05-02-2023","og_site_name":"TSV Ettlingen","article_published_time":"2023-02-04T06:47:30+00:00","article_modified_time":"2023-02-13T18:29:50+00:00","author":"Frank","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Frank","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tsv-ettlingen.de\/tsv\/9-heimspieltag-am-04-05-02-2023#article","isPartOf":{"@id":"https:\/\/tsv-ettlingen.de\/tsv\/9-heimspieltag-am-04-05-02-2023"},"author":{"name":"Frank","@id":"https:\/\/tsv-ettlingen.de\/tsv\/#\/schema\/person\/191ec17c3ce34b00891f4f8068a07459"},"headline":"9. Heimspieltag am 04.\/05.02.2023","datePublished":"2023-02-04T06:47:30+00:00","dateModified":"2023-02-13T18:29:50+00:00","mainEntityOfPage":{"@id":"https:\/\/tsv-ettlingen.de\/tsv\/9-heimspieltag-am-04-05-02-2023"},"wordCount":347,"commentCount":0,"publisher":{"@id":"https:\/\/tsv-ettlingen.de\/tsv\/#organization"},"articleSection":{"1":"Basketball"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tsv-ettlingen.de\/tsv\/9-heimspieltag-am-04-05-02-2023#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tsv-ettlingen.de\/tsv\/9-heimspieltag-am-04-05-02-2023","url":"https:\/\/tsv-ettlingen.de\/tsv\/9-heimspieltag-am-04-05-02-2023","name":"9. Heimspieltag am 04.\/05.02.2023 - TSV Ettlingen","isPartOf":{"@id":"https:\/\/tsv-ettlingen.de\/tsv\/#website"},"datePublished":"2023-02-04T06:47:30+00:00","dateModified":"2023-02-13T18:29:50+00:00","breadcrumb":{"@id":"https:\/\/tsv-ettlingen.de\/tsv\/9-heimspieltag-am-04-05-02-2023#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tsv-ettlingen.de\/tsv\/9-heimspieltag-am-04-05-02-2023"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/tsv-ettlingen.de\/tsv\/9-heimspieltag-am-04-05-02-2023#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/tsv-ettlingen.de\/tsv\/"},{"@type":"ListItem","position":2,"name":"9. Heimspieltag am 04.\/05.02.2023"}]},{"@type":"WebSite","@id":"https:\/\/tsv-ettlingen.de\/tsv\/#website","url":"https:\/\/tsv-ettlingen.de\/tsv\/","name":"TSV Ettlingen","description":"Zusammenhalt leben!","publisher":{"@id":"https:\/\/tsv-ettlingen.de\/tsv\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tsv-ettlingen.de\/tsv\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/tsv-ettlingen.de\/tsv\/#organization","name":"TSV Ettlingen e.V.","url":"https:\/\/tsv-ettlingen.de\/tsv\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/tsv-ettlingen.de\/tsv\/#\/schema\/logo\/image\/","url":"https:\/\/tsv-ettlingen.de\/tsv\/wp-content\/uploads\/2021\/05\/LOGO_Farbe.jpg","contentUrl":"https:\/\/tsv-ettlingen.de\/tsv\/wp-content\/uploads\/2021\/05\/LOGO_Farbe.jpg","width":2008,"height":1181,"caption":"TSV Ettlingen e.V."},"image":{"@id":"https:\/\/tsv-ettlingen.de\/tsv\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/tsv_ettlingen\/"]},{"@type":"Person","@id":"https:\/\/tsv-ettlingen.de\/tsv\/#\/schema\/person\/191ec17c3ce34b00891f4f8068a07459","name":"Frank","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/b27f9d77b987be88a5739765b8f2ebb9cdd50622de5561c0cd970dae24e7f7d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b27f9d77b987be88a5739765b8f2ebb9cdd50622de5561c0cd970dae24e7f7d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b27f9d77b987be88a5739765b8f2ebb9cdd50622de5561c0cd970dae24e7f7d3?s=96&d=mm&r=g","caption":"Frank"},"sameAs":["http:\/\/www.spiders.de"],"url":"https:\/\/tsv-ettlingen.de\/tsv\/author\/frankrau"}]}},"_links":{"self":[{"href":"https:\/\/tsv-ettlingen.de\/tsv\/wp-json\/wp\/v2\/posts\/2305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tsv-ettlingen.de\/tsv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tsv-ettlingen.de\/tsv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tsv-ettlingen.de\/tsv\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/tsv-ettlingen.de\/tsv\/wp-json\/wp\/v2\/comments?post=2305"}],"version-history":[{"count":3,"href":"https:\/\/tsv-ettlingen.de\/tsv\/wp-json\/wp\/v2\/posts\/2305\/revisions"}],"predecessor-version":[{"id":2312,"href":"https:\/\/tsv-ettlingen.de\/tsv\/wp-json\/wp\/v2\/posts\/2305\/revisions\/2312"}],"wp:attachment":[{"href":"https:\/\/tsv-ettlingen.de\/tsv\/wp-json\/wp\/v2\/media?parent=2305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tsv-ettlingen.de\/tsv\/wp-json\/wp\/v2\/categories?post=2305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tsv-ettlingen.de\/tsv\/wp-json\/wp\/v2\/tags?post=2305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}