{"id":5156,"date":"2026-02-05T17:16:25","date_gmt":"2026-02-05T16:16:25","guid":{"rendered":"https:\/\/tsv-ettlingen.de\/tsv\/?p=5156"},"modified":"2026-02-10T17:26:35","modified_gmt":"2026-02-10T16:26:35","slug":"damen-1-liefern-sich-beim-tabellenfuehrer-starken-kampf","status":"publish","type":"post","link":"https:\/\/tsv-ettlingen.de\/tsv\/damen-1-liefern-sich-beim-tabellenfuehrer-starken-kampf","title":{"rendered":"Damen 1 liefern sich beim Tabellenf\u00fchrer starken Kampf"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Die Damen 1 des TSV mussten sich am vergangenen Spieltag dem Tabellenf\u00fchrer SSC Karlsruhe geschlagen geben, zeigten dabei jedoch eine starke k\u00e4mpferische Leistung und bewiesen, dass sie auch mit den Top-Teams der Oberliga mithalten k\u00f6nnen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Trotz eines holprigen Starts gelang es dem Team, das erste Viertel offen zu gestalten und mit 15:11 in Reichweite zu bleiben. Auch im weiteren Spielverlauf lie\u00df man den SSC nie entscheidend davonziehen \u2013 der maximale Vorsprung der Karlsruherinnen betrug lediglich elf Punkte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Besonders das dritte Viertel war aus Ettlinger Sicht herausragend. Mit starkem Teamplay, konzentrierter Defense und gutem Ballvortrag gewann der TSV diesen Abschnitt verdient mit 13:18 und hielt die Partie weiterhin spannend. Im Schlussviertel entwickelte sich ein ausgeglichenes Spiel auf Augenh\u00f6he. Wenige Sekunden vor dem Ende schaffte es Ettlingen nicht mehr, den Ausgleich zu erzielen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ausschlaggebend f\u00fcr die knappe Niederlage waren letztlich Ballverluste in der eigenen H\u00e4lfte sowie eine schwache Freiwurfquote. Dennoch war es insgesamt eine sehr gute Mannschaftsleistung. Die Partie verlief zudem jederzeit fair und war ein gutes Oberliga-Spiel zweier starker Teams.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hervorzuheben ist die Leistung von Melina Kleinhans, die \u00fcber die gesamte Spielzeit hinweg eine starke Vorstellung zeigte. Sie leitete das Spiel mit viel \u00dcbersicht und Ruhe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mit dieser Leistung blickt das Team trotz der Niederlage optimistisch auf das kommende Wochenende. Am Samstag wartet mit dem Spiel gegen den Tabellenvorletzten aus Wieblingen eines der wichtigsten Spiele der Saison. Im direkten Abstiegskampf geht es darum, mit einem Sieg den Konkurrenten auf Distanz zu halten. Die gezeigte Leistung gegen den Tabellenf\u00fchrer macht dabei Mut.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading has-neve-link-color-color has-text-color has-link-color wp-elements-a9fd4dc07f36b2043b8c60dae37f72b4\"><strong>Grizzlies SSC Karlsruhe &#8211; TSV Ettlingen 1<\/strong>\u00a0    <strong>61:57<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Viertelergebnisse:<\/strong>\u00a015:11, 16:11, 13:18, 17:17<br><strong>Es spielten:\u00a0<\/strong>Carina Ruff (15 Punkte), Melina Kleinhans (14), \u00a0Pamina Ritz (8), Caroline Riemann (8), Mika Murakami (6), Louisa Krausz (6), Shirley Kim Braun und Kate Victoria Scheibli<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Damen 1 des TSV mussten sich am vergangenen Spieltag dem Tabellenf\u00fchrer SSC Karlsruhe geschlagen geben, zeigten dabei jedoch eine starke k\u00e4mpferische Leistung und bewiesen, dass sie auch mit den Top-Teams der Oberliga mithalten k\u00f6nnen. Trotz eines holprigen Starts gelang es dem Team, das erste Viertel offen zu gestalten und mit 15:11 in Reichweite zu&hellip;&nbsp;<a href=\"https:\/\/tsv-ettlingen.de\/tsv\/damen-1-liefern-sich-beim-tabellenfuehrer-starken-kampf\" rel=\"bookmark\">Weiterlesen &raquo;<span class=\"screen-reader-text\">Damen 1 liefern sich beim Tabellenf\u00fchrer starken Kampf<\/span><\/a><\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[18],"tags":[384,77,55,202,53],"class_list":["post-5156","post","type-post","status-publish","format-standard","hentry","category-basketball","tag-auswaertsniederlage","tag-damen-1","tag-landesliga","tag-ssc-karlsruhe","tag-tabellenfuehrer"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Damen 1 liefern sich beim Tabellenf\u00fchrer starken Kampf - TSV Ettlingen<\/title>\n<meta name=\"description\" content=\"Die Damen 1 mussten sich dem Tabellenf\u00fchrer SSC Karlsruhe geschlagen geben, zeigten dabei jedoch eine starke k\u00e4mpferische Leistung.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tsv-ettlingen.de\/tsv\/damen-1-liefern-sich-beim-tabellenfuehrer-starken-kampf\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Damen 1 liefern sich beim Tabellenf\u00fchrer starken Kampf - TSV Ettlingen\" \/>\n<meta property=\"og:description\" content=\"Die Damen 1 mussten sich dem Tabellenf\u00fchrer SSC Karlsruhe geschlagen geben, zeigten dabei jedoch eine starke k\u00e4mpferische Leistung.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tsv-ettlingen.de\/tsv\/damen-1-liefern-sich-beim-tabellenfuehrer-starken-kampf\" \/>\n<meta property=\"og:site_name\" content=\"TSV Ettlingen\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-05T16:16:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-10T16:26:35+00:00\" \/>\n<meta name=\"author\" content=\"Nina Skala\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nina Skala\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/damen-1-liefern-sich-beim-tabellenfuehrer-starken-kampf#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/damen-1-liefern-sich-beim-tabellenfuehrer-starken-kampf\"},\"author\":{\"name\":\"Nina Skala\",\"@id\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/#\\\/schema\\\/person\\\/4fe29ec5d992d5063165bd153dfa8f5a\"},\"headline\":\"Damen 1 liefern sich beim Tabellenf\u00fchrer starken Kampf\",\"datePublished\":\"2026-02-05T16:16:25+00:00\",\"dateModified\":\"2026-02-10T16:26:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/damen-1-liefern-sich-beim-tabellenfuehrer-starken-kampf\"},\"wordCount\":291,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/#organization\"},\"keywords\":[\"Ausw\u00e4rtsniederlage\",\"Damen 1\",\"Landesliga\",\"SSC Karlsruhe\",\"Tabellenf\u00fchrer\"],\"articleSection\":[\"Basketball\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/damen-1-liefern-sich-beim-tabellenfuehrer-starken-kampf#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/damen-1-liefern-sich-beim-tabellenfuehrer-starken-kampf\",\"url\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/damen-1-liefern-sich-beim-tabellenfuehrer-starken-kampf\",\"name\":\"Damen 1 liefern sich beim Tabellenf\u00fchrer starken Kampf - TSV Ettlingen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/#website\"},\"datePublished\":\"2026-02-05T16:16:25+00:00\",\"dateModified\":\"2026-02-10T16:26:35+00:00\",\"description\":\"Die Damen 1 mussten sich dem Tabellenf\u00fchrer SSC Karlsruhe geschlagen geben, zeigten dabei jedoch eine starke k\u00e4mpferische Leistung.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/damen-1-liefern-sich-beim-tabellenfuehrer-starken-kampf#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/damen-1-liefern-sich-beim-tabellenfuehrer-starken-kampf\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/damen-1-liefern-sich-beim-tabellenfuehrer-starken-kampf#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Damen 1 liefern sich beim Tabellenf\u00fchrer starken Kampf\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/#website\",\"url\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/\",\"name\":\"TSV Ettlingen\",\"description\":\"Zusammenhalt leben!\",\"publisher\":{\"@id\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/#organization\",\"name\":\"TSV Ettlingen e.V.\",\"url\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/LOGO_Farbe.jpg\",\"contentUrl\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/LOGO_Farbe.jpg\",\"width\":2008,\"height\":1181,\"caption\":\"TSV Ettlingen e.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/tsv_ettlingen\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/#\\\/schema\\\/person\\\/4fe29ec5d992d5063165bd153dfa8f5a\",\"name\":\"Nina Skala\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/213999610ce51a277c47ed9436e7468b593e7e2ccfccac0a98a78b3a688f3f60?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/213999610ce51a277c47ed9436e7468b593e7e2ccfccac0a98a78b3a688f3f60?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/213999610ce51a277c47ed9436e7468b593e7e2ccfccac0a98a78b3a688f3f60?s=96&d=mm&r=g\",\"caption\":\"Nina Skala\"},\"url\":\"https:\\\/\\\/tsv-ettlingen.de\\\/tsv\\\/author\\\/ninaskala\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Damen 1 liefern sich beim Tabellenf\u00fchrer starken Kampf - TSV Ettlingen","description":"Die Damen 1 mussten sich dem Tabellenf\u00fchrer SSC Karlsruhe geschlagen geben, zeigten dabei jedoch eine starke k\u00e4mpferische Leistung.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tsv-ettlingen.de\/tsv\/damen-1-liefern-sich-beim-tabellenfuehrer-starken-kampf","og_locale":"de_DE","og_type":"article","og_title":"Damen 1 liefern sich beim Tabellenf\u00fchrer starken Kampf - TSV Ettlingen","og_description":"Die Damen 1 mussten sich dem Tabellenf\u00fchrer SSC Karlsruhe geschlagen geben, zeigten dabei jedoch eine starke k\u00e4mpferische Leistung.","og_url":"https:\/\/tsv-ettlingen.de\/tsv\/damen-1-liefern-sich-beim-tabellenfuehrer-starken-kampf","og_site_name":"TSV Ettlingen","article_published_time":"2026-02-05T16:16:25+00:00","article_modified_time":"2026-02-10T16:26:35+00:00","author":"Nina Skala","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Nina Skala","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tsv-ettlingen.de\/tsv\/damen-1-liefern-sich-beim-tabellenfuehrer-starken-kampf#article","isPartOf":{"@id":"https:\/\/tsv-ettlingen.de\/tsv\/damen-1-liefern-sich-beim-tabellenfuehrer-starken-kampf"},"author":{"name":"Nina Skala","@id":"https:\/\/tsv-ettlingen.de\/tsv\/#\/schema\/person\/4fe29ec5d992d5063165bd153dfa8f5a"},"headline":"Damen 1 liefern sich beim Tabellenf\u00fchrer starken Kampf","datePublished":"2026-02-05T16:16:25+00:00","dateModified":"2026-02-10T16:26:35+00:00","mainEntityOfPage":{"@id":"https:\/\/tsv-ettlingen.de\/tsv\/damen-1-liefern-sich-beim-tabellenfuehrer-starken-kampf"},"wordCount":291,"commentCount":0,"publisher":{"@id":"https:\/\/tsv-ettlingen.de\/tsv\/#organization"},"keywords":["Ausw\u00e4rtsniederlage","Damen 1","Landesliga","SSC Karlsruhe","Tabellenf\u00fchrer"],"articleSection":["Basketball"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tsv-ettlingen.de\/tsv\/damen-1-liefern-sich-beim-tabellenfuehrer-starken-kampf#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tsv-ettlingen.de\/tsv\/damen-1-liefern-sich-beim-tabellenfuehrer-starken-kampf","url":"https:\/\/tsv-ettlingen.de\/tsv\/damen-1-liefern-sich-beim-tabellenfuehrer-starken-kampf","name":"Damen 1 liefern sich beim Tabellenf\u00fchrer starken Kampf - TSV Ettlingen","isPartOf":{"@id":"https:\/\/tsv-ettlingen.de\/tsv\/#website"},"datePublished":"2026-02-05T16:16:25+00:00","dateModified":"2026-02-10T16:26:35+00:00","description":"Die Damen 1 mussten sich dem Tabellenf\u00fchrer SSC Karlsruhe geschlagen geben, zeigten dabei jedoch eine starke k\u00e4mpferische Leistung.","breadcrumb":{"@id":"https:\/\/tsv-ettlingen.de\/tsv\/damen-1-liefern-sich-beim-tabellenfuehrer-starken-kampf#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tsv-ettlingen.de\/tsv\/damen-1-liefern-sich-beim-tabellenfuehrer-starken-kampf"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/tsv-ettlingen.de\/tsv\/damen-1-liefern-sich-beim-tabellenfuehrer-starken-kampf#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/tsv-ettlingen.de\/tsv\/"},{"@type":"ListItem","position":2,"name":"Damen 1 liefern sich beim Tabellenf\u00fchrer starken Kampf"}]},{"@type":"WebSite","@id":"https:\/\/tsv-ettlingen.de\/tsv\/#website","url":"https:\/\/tsv-ettlingen.de\/tsv\/","name":"TSV Ettlingen","description":"Zusammenhalt leben!","publisher":{"@id":"https:\/\/tsv-ettlingen.de\/tsv\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tsv-ettlingen.de\/tsv\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/tsv-ettlingen.de\/tsv\/#organization","name":"TSV Ettlingen e.V.","url":"https:\/\/tsv-ettlingen.de\/tsv\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/tsv-ettlingen.de\/tsv\/#\/schema\/logo\/image\/","url":"https:\/\/tsv-ettlingen.de\/tsv\/wp-content\/uploads\/2021\/05\/LOGO_Farbe.jpg","contentUrl":"https:\/\/tsv-ettlingen.de\/tsv\/wp-content\/uploads\/2021\/05\/LOGO_Farbe.jpg","width":2008,"height":1181,"caption":"TSV Ettlingen e.V."},"image":{"@id":"https:\/\/tsv-ettlingen.de\/tsv\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/tsv_ettlingen\/"]},{"@type":"Person","@id":"https:\/\/tsv-ettlingen.de\/tsv\/#\/schema\/person\/4fe29ec5d992d5063165bd153dfa8f5a","name":"Nina Skala","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/213999610ce51a277c47ed9436e7468b593e7e2ccfccac0a98a78b3a688f3f60?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/213999610ce51a277c47ed9436e7468b593e7e2ccfccac0a98a78b3a688f3f60?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/213999610ce51a277c47ed9436e7468b593e7e2ccfccac0a98a78b3a688f3f60?s=96&d=mm&r=g","caption":"Nina Skala"},"url":"https:\/\/tsv-ettlingen.de\/tsv\/author\/ninaskala"}]}},"_links":{"self":[{"href":"https:\/\/tsv-ettlingen.de\/tsv\/wp-json\/wp\/v2\/posts\/5156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tsv-ettlingen.de\/tsv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tsv-ettlingen.de\/tsv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tsv-ettlingen.de\/tsv\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/tsv-ettlingen.de\/tsv\/wp-json\/wp\/v2\/comments?post=5156"}],"version-history":[{"count":1,"href":"https:\/\/tsv-ettlingen.de\/tsv\/wp-json\/wp\/v2\/posts\/5156\/revisions"}],"predecessor-version":[{"id":5157,"href":"https:\/\/tsv-ettlingen.de\/tsv\/wp-json\/wp\/v2\/posts\/5156\/revisions\/5157"}],"wp:attachment":[{"href":"https:\/\/tsv-ettlingen.de\/tsv\/wp-json\/wp\/v2\/media?parent=5156"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tsv-ettlingen.de\/tsv\/wp-json\/wp\/v2\/categories?post=5156"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tsv-ettlingen.de\/tsv\/wp-json\/wp\/v2\/tags?post=5156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}